{"id":4551,"date":"2023-07-05T08:20:07","date_gmt":"2023-07-05T06:20:07","guid":{"rendered":"https:\/\/merca.presspulp.com\/obsolescence-des-competences\/"},"modified":"2025-08-26T16:27:31","modified_gmt":"2025-08-26T14:27:31","slug":"obsolescencia-de-competencias","status":"publish","type":"post","link":"https:\/\/merca.team\/es\/obsolescence-des-competences\/","title":{"rendered":"Anticipar y evitar la obsolescencia de competencias en 2025"},"content":{"rendered":"<ul class=\"wp-block-list\">\n<li>Los asalariados m\u00e1s afectados por la obsolescencia de las competencias son los trabajadores de m\u00e1s edad (31 % de las personas de 50 a 55 a\u00f1os se ven afectadas por el problema, frente a 21 % de las de 30 a 39 a\u00f1os, seg\u00fan una encuesta del CEDEFOP), los menos cualificados (33 % de las personas poco cualificadas afectadas, frente a 19 % de las que tienen una cualificaci\u00f3n alta) y los trabajadores que no reciben formaci\u00f3n continua (34 %, frente a 22 % de los que s\u00ed la reciben).<br><\/li>\n\n\n\n<li>La OCDE se\u00f1ala que la vida \u00fatil de una competencia t\u00e9cnica ha pasado de 30 a\u00f1os en 1987 a 2 a\u00f1os en la actualidad, consecuencia inevitable del progreso tecnol\u00f3gico.<br><\/li>\n\n\n\n<li><strong>85%<\/strong>&nbsp;de los empleos de 2030 a\u00fan no existen? Otra estad\u00edstica aterradora: en un estudio realizado para&nbsp;<a href=\"https:\/\/www.fujitsu.com\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fujitsu<\/a>&nbsp;por el consultor Pierre Audoin,&nbsp;<strong>88%<\/strong>&nbsp;de los encuestados creen que, en 2025, el auge de la inteligencia artificial ser\u00e1 uno de los tres factores que configurar\u00e1n el mundo laboral.<br><\/li>\n\n\n\n<li><a href=\"https:\/\/www.latribune.fr\/entreprises-finance\/automatisation-375-millions-de-personnes-forcees-de-changer-d-emploi-d-ici-2030-759893.html\" target=\"_blank\" rel=\"noreferrer noopener\">Mckinsey <\/a>afirm\u00f3 en 2017 que 50% de las profesiones ya podr\u00edan automatizarse. Adem\u00e1s,&nbsp;<strong>Hasta un tercio de las actividades podr\u00edan ser sustituidas de aqu\u00ed a 2030, lo que obligar\u00eda a cambiar de sector a entre 75 y 375 millones de trabajadores.<\/strong><br><\/li>\n\n\n\n<li><strong>la vida \u00fatil de una competencia t\u00e9cnica es ahora de s\u00f3lo 12 a 18 meses<\/strong>&nbsp;y esta media desciende dr\u00e1sticamente en las profesiones digitales (a poco m\u00e1s de 3 meses).<br><\/li>\n\n\n\n<li>Los trabajadores m\u00e1s perjudicados son los de m\u00e1s edad (31 % de 50-55 a\u00f1os), los menos cualificados (33 %) y los que no participan en la formaci\u00f3n continua (34 %).<br><\/li>\n\n\n\n<li><strong>33%<\/strong> Los trabajadores franceses estar\u00e1n jubilados en 2030: Fuente: proyecci\u00f3n del Conseil d'orientation des retraites, 2019<br><\/li>\n\n\n\n<li>CEDEFOP (<em>Centro Europeo para el Desarrollo y la Formaci\u00f3n Profesional<\/em>) menciona cuatro tipos de obsolescencia de las competencias:<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"obsolescence-des-competences-introduction\">Obsolescencia de las competencias: introducci\u00f3n <\/h2>\n\n\n\n<p>Anticiparse a la obsolescencia de las competencias se ha convertido en una necesidad ineludible en el mundo laboral actual. Seg\u00fan <a href=\"https:\/\/www.delltechnologies.com\/content\/dam\/delltechnologies\/assets\/perspectives\/2030\/pdf\/SR1940_IFTFforDellTechnologies_Human-Machine_070517_readerhigh-res.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">un estudio del Instituto para el Futuro (IFTF)<\/a>Se calcula que 85% de las ocupaciones que existir\u00e1n en 2030 a\u00fan no se han creado. Al mismo tiempo, Mckinsey predice que entre 75 y 375 millones de trabajadores podr\u00edan tener que cambiar de especialidad en 2030, debido a la r\u00e1pida evoluci\u00f3n de las competencias requeridas. Ante estos cambios significativos, comprender c\u00f3mo anticipar y gestionar la obsolescencia de las competencias es m\u00e1s crucial que nunca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/merca.team\/es\/webinarios-eventos\/como-bonduelle-transformo-la-gestion-de-sus-equipos-de-produccion-para-aumentar-la-productividad\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"299\" src=\"https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-1024x299.png\" alt=\"Obsolescencia de las competencias\" class=\"wp-image-7660\" srcset=\"https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-1024x299.png 1024w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-88x26.png 88w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-300x88.png 300w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-768x224.png 768w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-1536x448.png 1536w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-2048x598.png 2048w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-18x5.png 18w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-1264x369.png 1264w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-182x53.png 182w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-100x29.png 100w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-830x242.png 830w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-450x131.png 450w, https:\/\/merca.team\/wp-content\/uploads\/2023\/07\/Banniere_Webinar_Bonduelle-1-1-2-360x105.png 360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"comprendre-lobsolescence-des-competences\">Comprender la obsolescencia de las competencias<\/h2>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-definition-de-l-obsolescence-des-competences\">A. Definici\u00f3n de obsolescencia de capacidades<\/h3>\n\n\n\n<p>La obsolescencia de las competencias, tal y como la defini\u00f3 Kaufman en 1974, se refiere a la inadecuaci\u00f3n de los conocimientos o competencias actualizados que necesita un trabajador para seguir siendo plenamente eficaz en su actividad profesional actual o futura. Este concepto pone de relieve el desfase que puede existir entre las competencias que posee un individuo y las que requiere su puesto de trabajo o su sector de actividad. Este desfase se ve a menudo acentuado por la r\u00e1pida evoluci\u00f3n de las tecnolog\u00edas y los m\u00e9todos de trabajo.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-les-profils-les-plus-touches-par-l-obsolescence-des-competences\">B. Perfiles m\u00e1s afectados por la obsolescencia de competencias<\/h3>\n\n\n\n<p>Hay que subrayar que la obsolescencia de las competencias no afecta a todos los trabajadores de la misma manera. Seg\u00fan <a href=\"https:\/\/www.cedefop.europa.eu\/files\/9070_fr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">una encuesta del CEDEFOP<\/a>Seg\u00fan la Comisi\u00f3n Europea, los trabajadores m\u00e1s afectados por la obsolescencia de las cualificaciones son los de m\u00e1s edad (31 % de las personas de 50-55 a\u00f1os se ven afectadas por el problema), los menos cualificados (33 % de las personas con un bajo nivel de cualificaci\u00f3n se ven afectadas, frente a 19 % de las que tienen un alto nivel de cualificaci\u00f3n) y los trabajadores que no reciben formaci\u00f3n continua (34 % se ven afectados, frente a 22 % de los que s\u00ed la reciben).<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-categories-d-obsolescence-des-competences\">C. Categor\u00edas de obsolescencia de competencias<\/h3>\n\n\n\n<p>Tambi\u00e9n es importante distinguir entre los distintos tipos de obsolescencia de las competencias:<\/p>\n\n\n\n<p><strong>Obsolescencia f\u00edsica de las competencias :<\/strong> Esta categor\u00eda se refiere al deterioro de las capacidades f\u00edsicas o cognitivas debido a la atrofia o al desgaste. Por ejemplo, un trabajador puede perder ciertas habilidades manuales con la edad o como consecuencia de una enfermedad.<\/p>\n\n\n\n<p><strong>Obsolescencia econ\u00f3mica de las competencias :<\/strong> Se produce cuando determinadas competencias, aunque todav\u00eda presentes, ya no son \u00fatiles o han perdido su importancia en un determinado puesto de trabajo. Este tipo de obsolescencia es especialmente frecuente en sectores en r\u00e1pida evoluci\u00f3n como la tecnolog\u00eda digital y la rob\u00f3tica.<\/p>\n\n\n\n<p><strong>Supervisi\u00f3n organizativa :<\/strong> Seg\u00fan el CEDEFOP, el olvido organizativo se produce cuando una empresa pierde competencias espec\u00edficas debido a la rotaci\u00f3n de personal.<\/p>\n\n\n\n<p><strong>Obsolescencia perspectivista :<\/strong> Se refiere a percepciones y creencias anticuadas sobre el trabajo y el entorno laboral.<\/p>\n\n\n\n<p>Estos diferentes tipos de obsolescencia ilustran la complejidad del fen\u00f3meno y la diversidad de factores que pueden contribuir a la obsolescencia de las competencias.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"pourquoi-anticiper-les-besoins-en-competences-de-demain\">\u00bfPor qu\u00e9 anticiparse a las necesidades de ma\u00f1ana?<\/h2>\n\n\n\n<p>La obsolescencia de las competencias repercute directamente en el rendimiento de las personas y las organizaciones. Con la r\u00e1pida evoluci\u00f3n del mundo laboral, algunas competencias pueden quedar r\u00e1pidamente obsoletas. Por ejemplo, seg\u00fan la OCDE, la vida \u00fatil de una cualificaci\u00f3n t\u00e9cnica ha pasado de 30 a\u00f1os en 1987 a 2 a\u00f1os en la actualidad. Este fen\u00f3meno de obsolescencia puede obstaculizar la productividad, la competitividad e incluso la supervivencia de las empresas.<\/p>\n\n\n\n<p>Por otra parte, esta r\u00e1pida evoluci\u00f3n de las competencias requeridas puede suponer una amenaza para la empleabilidad de los trabajadores. De hecho, McKinsey predice que entre 75 y 375 millones de trabajadores podr\u00edan verse obligados a cambiar de campo de aqu\u00ed a 2030, debido a la r\u00e1pida evoluci\u00f3n de las competencias requeridas.<\/p>\n\n\n\n<p>Ante estos retos, es fundamental anticiparse a las necesidades de ma\u00f1ana en materia de competencias. Esta anticipaci\u00f3n permite mantener la empleabilidad de los trabajadores, la competitividad de las empresas y el dinamismo de las econom\u00edas. Tambi\u00e9n es una condici\u00f3n esencial para hacer frente a<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"les-enjeux-dune-gestion-des-competences-efficace\">Los retos de una gesti\u00f3n eficaz de las competencias<\/h2>\n\n\n\n<p>La <a href=\"https:\/\/merca.team\/es\/matriz-de-competencias\/\">gesti\u00f3n de competencias<\/a> es un componente esencial de la competitividad y la sostenibilidad de una organizaci\u00f3n. En este contexto, hay dos elementos especialmente importantes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Mantener actualizado el inventario de competencias de la empresa:<\/strong> Al identificar y supervisar peri\u00f3dicamente las competencias disponibles en la empresa, las organizaciones pueden adaptarse a los cambios del entorno y anticiparse al riesgo de que las competencias se queden obsoletas. Este inventario de competencias tambi\u00e9n es esencial para planificar y poner en marcha las iniciativas de formaci\u00f3n necesarias.<\/li>\n\n\n\n<li><strong>Apoyar los itinerarios de cualificaci\u00f3n :<\/strong> La gesti\u00f3n de las competencias no consiste s\u00f3lo en identificarlas. Tambi\u00e9n es esencial apoyar a los trabajadores en el desarrollo de sus capacidades, ya sea mediante formaci\u00f3n, asesoramiento, tutor\u00eda u otras formas de apoyo. Este apoyo contribuye no s\u00f3lo a la empleabilidad de los trabajadores, sino tambi\u00e9n a la competitividad y sostenibilidad de la empresa.<\/li>\n<\/ol>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"comment-remedier-a-la-perte-de-competences\">C\u00f3mo remediar la p\u00e9rdida de competencias<\/h2>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"a-le-plan-de-transfert-de-competences\">A. El Plan de Transferencia de Competencias<\/h3>\n\n\n\n<p>Dada la r\u00e1pida obsolescencia de las competencias, es vital poner en marcha un plan de transferencia de competencias.<\/p>\n\n\n\n<p>Anticipar y gestionar la obsolescencia de competencias requiere una estrategia clara y bien estructurada que identifique los puestos cr\u00edticos en los que una p\u00e9rdida de conocimientos podr\u00eda ser un problema importante para la empresa. En el centro de esta estrategia est\u00e1 el plan de transferencia de competencias.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Identificaci\u00f3n de puestos cr\u00edticos<\/strong> Identifique los puestos cr\u00edticos en los que una p\u00e9rdida de conocimientos podr\u00eda representar un riesgo importante para su organizaci\u00f3n. Este es el primer paso para desarrollar un plan eficaz de transferencia de competencias.<\/li>\n\n\n\n<li><strong>Definici\u00f3n de objetivos y estrategias de transferencia de competencias<\/strong> Una vez identificados los puestos cr\u00edticos, es esencial definir claramente los objetivos de transferencia de competencias. Estos objetivos deben incluir el mapeo de competencias, la gesti\u00f3n de riesgos, la minimizaci\u00f3n de la p\u00e9rdida de productividad y la gesti\u00f3n de la escasez de mano de obra.<\/li>\n\n\n\n<li><strong>Fomentar una cultura de formaci\u00f3n e intercambio de conocimientos<\/strong> Para que la transferencia de competencias sea eficaz, es necesario desarrollar y fomentar una cultura de aprendizaje continuo e intercambio de conocimientos. T\u00e9cnicas como la tutor\u00eda, el patrocinio y el coaching pueden utilizarse para fomentar el intercambio de conocimientos.<\/li>\n\n\n\n<li><strong>Inversi\u00f3n en tecnolog\u00edas y recursos adecuados<\/strong> El uso de tecnolog\u00edas apropiadas y la inversi\u00f3n en recursos adaptados a su realidad (como plataformas virtuales, libros y comunidades de pr\u00e1ctica) son esenciales para facilitar la transferencia de competencias.<\/li>\n\n\n\n<li><strong>Reconocer los esfuerzos y apoyar las iniciativas de transferencia de competencias<\/strong> Es importante reconocer los \u00e9xitos y animar a los directivos a apoyar activamente las iniciativas de transferencia de competencias.<\/li>\n\n\n\n<li><strong>Valorar el compromiso y la motivaci\u00f3n<\/strong> La implantaci\u00f3n de una cultura del reconocimiento puede estimular el compromiso y la motivaci\u00f3n de los empleados, dos elementos fundamentales en la lucha contra la obsolescencia de las competencias.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"b-valorisation-des-soft-skills\">B. Desarrollo de competencias interpersonales<\/h3>\n\n\n\n<p>Las competencias interpersonales desempe\u00f1an un papel fundamental en el mantenimiento de la empleabilidad y adaptabilidad de los trabajadores. Aunque es importante mantenerse a la vanguardia de las nuevas tecnolog\u00edas, ciertas competencias, como la creatividad, el pensamiento cr\u00edtico y la capacidad de trabajar en equipo, son insustituibles e inimitables por los robots.<\/p>\n\n\n\n<p>Al cultivar estas habilidades humanas e interpersonales, los empleados son capaces de mantener su ventaja competitiva, aprender continuamente y adaptarse con agilidad a cualquier cambio futuro. Tambi\u00e9n son m\u00e1s capaces de hacerse cargo de su propia empleabilidad, algo crucial en un entorno profesional en constante cambio.<\/p>\n\n\n\n<p>El papel de la empresa en esta din\u00e1mica es crucial. Por un lado, debe apoyar a los empleados para que puedan desarrollar estas competencias interpersonales de forma estrat\u00e9gica, de acuerdo con su funci\u00f3n dentro de la empresa. Por otra, debe crear un entorno propicio a la expresi\u00f3n de estas competencias, basado en la benevolencia y el respeto mutuo.<\/p>\n\n\n\n<p>Las competencias blandas no funcionan de forma aislada, sino que interact\u00faan entre s\u00ed, dando lugar a lo que se conoce como inteligencia colectiva. Al inculcar una cultura de benevolencia, la empresa puede fomentar la armon\u00eda dentro de sus equipos y optimizar el potencial de cada individuo. Este enfoque hol\u00edstico evita la obsolescencia de las competencias y prepara a la empresa para los retos futuros.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"c-utilisation-dun-logiciel-dedie-a-la-gestion-des-competences\">C. Utilizaci\u00f3n de programas inform\u00e1ticos dedicados a la gesti\u00f3n de competencias<\/h3>\n\n\n\n<p>En un mundo laboral cada vez m\u00e1s complejo y en constante evoluci\u00f3n, las soluciones inform\u00e1ticas de RRHH son esenciales. Entre ellas, Mercateam destaca por su enfoque centrado en el dominio de los conocimientos t\u00e9cnicos. Esta plataforma ofrece herramientas eficaces para gestionar e identificar las competencias clave, las autorizaciones, las restricciones y toda la informaci\u00f3n pertinente de cada empleado.<\/p>\n\n\n\n<p>Mercateam contribuye no s\u00f3lo a aumentar la agilidad y polivalencia de los equipos, sino tambi\u00e9n a mejorar su rendimiento global. A largo plazo, Mercateam ayuda a orientar los conocimientos t\u00e9cnicos de la empresa y a preparar a los empleados para los puestos de trabajo del ma\u00f1ana.<\/p>\n\n\n\n<p>Adem\u00e1s, gracias a las notificaciones y alertas que proporciona esta soluci\u00f3n inteligente, Mercateam permite anticiparse a las p\u00e9rdidas cr\u00edticas de conocimientos. Al cumplir los requisitos del C\u00f3digo Laboral, ofrece un apoyo inestimable a cualquier organizaci\u00f3n que desee seguir cumpliendo la normativa al tiempo que optimiza sus competencias.<\/p>\n\n\n\n<p>Ante la obsolescencia acelerada de las competencias, la adopci\u00f3n de soluciones inform\u00e1ticas de RRHH como Mercateam es esencial para cualquier organizaci\u00f3n que desee gestionar sus competencias de forma eficaz y anticiparse a las necesidades futuras.<\/p>\n\n\n\n<div style=\"height:5px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"d-l-importance-du-mentorat-du-parrainage-et-du-coaching\">D. La importancia de la tutor\u00eda, el patrocinio y el coaching<\/h3>\n\n\n\n<p>Por \u00faltimo, la tutor\u00eda, el patrocinio y el coaching son m\u00e9todos poderosos para fomentar la transferencia de competencias y el aprendizaje continuo. Fomentan una cultura de intercambio de conocimientos y formaci\u00f3n, esencial para evitar la obsolescencia de las competencias. Adem\u00e1s de apoyar el desarrollo profesional, estos enfoques contribuyen a reforzar el compromiso y la motivaci\u00f3n de los empleados, factores clave para el futuro a largo plazo de la empresa.<\/p>\n\n\n\n<p>Anticiparse a la obsolescencia de las competencias es vital para que las empresas sigan siendo competitivas en la era digital. Mediante una gesti\u00f3n proactiva, la inversi\u00f3n en formaci\u00f3n continua y la valorizaci\u00f3n de las competencias interpersonales, las empresas pueden convertir este reto en una oportunidad. Herramientas como Mercateam son aliados inestimables para navegar con \u00e9xito por este panorama en constante cambio.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Obsolescence des comp\u00e9tences : introduction Anticiper l&rsquo;obsolescence des comp\u00e9tences est devenue une n\u00e9cessit\u00e9 incontournable dans le monde du travail contemporain. Selon une \u00e9tude de l&rsquo;Institute for the Future (IFTF), il est estim\u00e9 que 85% des m\u00e9tiers qui existeront en 2030 n&rsquo;ont pas encore \u00e9t\u00e9 cr\u00e9\u00e9s. En parall\u00e8le, Mckinsey pr\u00e9voit qu&rsquo;entre 75 et 375 millions de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":4552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Anticiper et \u00e9viter l'obsolescence des comp\u00e9tences en 2023","_seopress_titles_desc":"Comment anticiper l'obsolescence des comp\u00e9tences dans le milieu industriel ?","_seopress_robots_index":"","_seopress_analysis_target_kw":"obsolescence des comp\u00e9tences","footnotes":""},"categories":[9,16],"tags":[],"class_list":["post-4551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-competences-habilitations","category-gpec-gepp"],"_links":{"self":[{"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/posts\/4551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/comments?post=4551"}],"version-history":[{"count":1,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/posts\/4551\/revisions"}],"predecessor-version":[{"id":9184,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/posts\/4551\/revisions\/9184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/media\/4552"}],"wp:attachment":[{"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/media?parent=4551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/categories?post=4551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/merca.team\/es\/wp-json\/wp\/v2\/tags?post=4551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}